{"id":8445,"date":"2022-10-13T06:55:50","date_gmt":"2022-10-13T05:55:50","guid":{"rendered":"https:\/\/mpc-services.be\/?page_id=8445"},"modified":"2022-11-28T06:31:51","modified_gmt":"2022-11-28T06:31:51","slug":"terms-of-service","status":"publish","type":"page","link":"https:\/\/mpc-services.be\/nl\/terms-of-service\/","title":{"rendered":"Terms of Service"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"8445\" class=\"elementor elementor-8445\" data-elementor-settings=\"{&quot;element_pack_global_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true}}\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fbf091d elementor-section-height-min-height elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-items-middle magic-button-disabled-no\" data-id=\"fbf091d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;shape_divider_bottom&quot;:&quot;arrow&quot;,&quot;shape_divider_bottom_negative&quot;:&quot;yes&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"true\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 700 10\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M360 0L350 9.9 340 0 0 0 0 10 700 10 700 0\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a64719a\" data-id=\"a64719a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-94845f9 elementor-widget elementor-widget-bdt-advanced-heading\" data-id=\"94845f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bdt-advanced-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"94845f9\" class=\"bdt-ep-advanced-heading\" data-settings=\"{&quot;titleMultiColor&quot;:&quot;no&quot;}\">\t\t\t<div class=\"bdt-ep-advanced-heading-sub-title\">\n\t\t\t\t<div class=\"bdt-ep-advanced-heading-sub-title-content\">\n\t\t\t\t\t\t\t\t\t\tMPC LUXURIOUS SERVICES \t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<h2 class=\"bdt-ep-advanced-heading-title\"><span class=\"bdt-ep-advanced-heading-main-title\"><span class=\"bdt-ep-advanced-heading-main-title-inner\">&nbsp;our cars for rent<\/span><\/span><\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7eee198 elementor-section-boxed elementor-section-height-default elementor-section-height-default magic-button-disabled-no\" data-id=\"7eee198\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2fd338d\" data-id=\"2fd338d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-332a53e elementor-widget elementor-widget-text-editor\" data-id=\"332a53e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong><u>Condition\u00a0g\u00e9n\u00e9rale :<\/u><\/strong><\/h2><p>Article 1. D\u00c9FINITIONS<\/p><p>Dans les pr\u00e9sentes Conditions g\u00e9n\u00e9rales, les termes repris ci-apr\u00e8s sont d\u00e9finis comme suit :<\/p><p>1.1. Le Chauffeur priv\u00e9 : une personne physique qui est occup\u00e9e par MPC Services \u00e0 titre de travailleur salari\u00e9, d\u2019ind\u00e9pendant, d&#8217;int\u00e9rimaire ou de sous-traitant. <br \/>1.2. Le temps de conduite : le temps qu&#8217;un Chauffeur priv\u00e9 passe \u00e0 conduire le v\u00e9hicule du Client, ce compris les pauses aux quelles peut pr\u00e9tendre le Chauffeur, \u00e0 savoir un quart d\u2019heure de pause par p\u00e9riode de quatre heures de conduite effective. <br \/>1.3. Le temps d&#8217;attente : le temps qu&#8217;un Chauffeur priv\u00e9 passe \u00e0 attendre le Client au cours de sa prestation de services en faveur de ce Client, quel que soit le motif de cette attente.<br \/>1.4. Le temps de prestation : la somme des temps de conduite et d\u2019attente au service du client depuis le lieu de d\u00e9part convenu jusqu\u2019\u00e0 l\u2019adresse convenue, et ce, \u00e0 l\u2019aller comme au retour.<br \/>1.5. Les Activit\u00e9s : toutes formes de prestation de services se rapportant \u00e0 l\u2019intervention d\u2019MPC Services entre des Clients et les Chauffeurs priv\u00e9s.<\/p><p>Article 2. DISPOSITIONS GENERALES<\/p><p>Les pr\u00e9sentes conditions g\u00e9n\u00e9rales d\u00e9finissent, sans pr\u00e9judices de l\u2019application de conditions particuli\u00e8res, les obligations respectives des parties contractantes \u00e0 l\u2019occasion des ventes\/prestations de services effectu\u00e9es par MPC Services.<br \/>En signant la convention ou le bon de commande, ou en acceptant la confirmation d\u2019une commande, notre cocontractant reconna\u00eet express\u00e9ment avoir pris connaissance des pr\u00e9sentes conditions g\u00e9n\u00e9rales et les avoir accept\u00e9es.<br \/>Les dispositions auxquelles il n\u2019est pas d\u00e9rog\u00e9 express\u00e9ment sont d\u2019application. Seules les d\u00e9rogations faisant l\u2019objet d\u2019un accord \u00e9crit d\u2019MPC Services peuvent modifier l\u2019application des pr\u00e9sentes conditions g\u00e9n\u00e9rales.<br \/>En cas de divergences entre les conditions g\u00e9n\u00e9rales de nos cocontractants et les n\u00f4tres, il est convenu que ces derni\u00e8res pr\u00e9vaudront.<\/p><p>Article 3. CHOIX DU CHAUFFEUR<\/p><p>MPC Services est enti\u00e8rement libre dans le choix des chauffeurs priv\u00e9s.<\/p><p>Article 4. OFFRES DE SERVICES<\/p><p>Nos offres de services sont totalement sans engagement de notre part.<\/p><p>Article 5. COMMANDE &#8211; CONFIRMATION<\/p><p>Toute commande qui nous est adress\u00e9e ne nous engage qu\u2019apr\u00e8s confirmation \u00e9crite de notre part.<br \/>Les commandes doivent \u00eatre effectu\u00e9es 24 heures \u00e0 l&#8217;avance. Toute r\u00e9servation effectu\u00e9e en urgence, c&#8217;est-\u00e0-dire le jour m\u00eame de la prestation, sera major\u00e9e de 10%. Les modifications apport\u00e9es par le client \u00e0 son contrat, son bon de commande ou \u00e0 notre offre ne seront valables qu\u2019\u00e0 la condition que nous les ayons accept\u00e9es et confirm\u00e9es par \u00e9crit.<br \/>Si le Client rel\u00e8ve une erreur ou une inexactitude dans le libell\u00e9 de notre confirmation, il doit imm\u00e9diatement en avertir MPC Services, et ce, au plus tard 12 heures avant le d\u00e9but de la prestation concern\u00e9e. Pass\u00e9 ce d\u00e9lai, MPC Services se r\u00e9serve le droit d\u2019annuler la commande sans que le Client puisse r\u00e9clamer la moindre indemnit\u00e9.<\/p><p>Article 6. ANNULATION D\u2019UNE COMMANDE<\/p><p>Les parties pourront annuler sans frais et par \u00e9crit (lettre, mail, fax) une commande au plus tard 24 heures avant le d\u00e9but de la prestation convenue. <br \/>Si le Client annule une commande moins de 24 heures avant le d\u00e9but de la prestation, pour quelque motif que ce soit, MPC Services pourra lui facturer un montant \u00e9quivalant \u00e0 3 heures de prestation d\u2019un chauffeur priv\u00e9.<\/p><p>Article 7. R\u00c9SILIATION<\/p><p>Sans pr\u00e9judice de l\u2019application des autres articles des pr\u00e9sentes conditions g\u00e9n\u00e9rales, nous nous r\u00e9servons le droit de suspendre ou de r\u00e9silier un contrat, sans avertissement ou mise en demeure quelconque, et sans qu&#8217;une intervention judiciaire ne soit requise, si le cocontractant : <br \/>1. n&#8217;ex\u00e9cute pas sa part du contrat; <br \/>2. est d\u00e9clar\u00e9 en faillite, ou qu&#8217;une telle proc\u00e9dure est demand\u00e9e; <br \/>3. a obtenu une proc\u00e9dure de r\u00e9organisation judiciaire, ou qu&#8217;une telle proc\u00e9dure est demand\u00e9e; <br \/>4. est concern\u00e9e par un r\u00e9gime de r\u00e8glement de dettes ou qu&#8217;une telle proc\u00e9dure est demand\u00e9e; <br \/>5. voit son entreprise cesser totalement ou partiellement ses activit\u00e9s; <br \/>6. perd une autorisation, une dispense ou une immatriculation n\u00e9cessaire \u00e0 son entreprise; <br \/>7. est confront\u00e9e \u00e0 une saisie, quelle qu&#8217;en soit la nature; <br \/>8. d\u00e9c\u00e8de, ou entame la liquidation (totale ou partielle) de son entreprise et\/ou de son patrimoine ; <br \/>9. est condamn\u00e9e de mani\u00e8re irr\u00e9vocable \u00e0 une peine d&#8217;emprisonnement ou n&#8217;est plus en mesure de respecter les obligations d\u00e9coulant du pr\u00e9sent contrat. <br \/>Si une des situations pr\u00e9cit\u00e9es s&#8217;applique, nous nous r\u00e9servons \u00e9galement le droit de r\u00e9clamer l&#8217;indemnisation de dommages directs et indirects, frais et int\u00e9r\u00eats.<\/p><p>Article 8. EX\u00c9CUTION DES ACTIVIT\u00c9S<\/p><p>Les activit\u00e9s convenues seront ex\u00e9cut\u00e9es aux jour(s) et heures convenus, dans les conditions convenues, apr\u00e8s confirmation \u00e9crite de notre part, sauf cas de force majeure.<\/p><p>Article 9. FORCE MAJEURE<\/p><p>9.1. En cas de force majeure, l&#8217;ex\u00e9cution du contrat peut \u00eatre suspendue, en tout ou en partie, jusqu&#8217;\u00e0 ce que la cause de la force majeure ait cess\u00e9, en tout ou en partie. Le contrat peut \u00e9galement dans ces circonstances \u00eatre r\u00e9sili\u00e9, en tout ou en partie, sans intervention judiciaire, et ce, sans qu\u2019une partie puisse r\u00e9clamer aucun droit \u00e0 l\u2019autre. Dans ce cas, le Client s\u2019oblige \u00e0 payer \u00e0 MPC Services les prestations au prorata de ce qui aura \u00e9t\u00e9 effectivement prest\u00e9 jusqu\u2019au moment de la suspension ou de la r\u00e9siliation.<br \/>9.2. La d\u00e9finition de la force majeure correspond \u00e0 tout \u00e9v\u00e9nement limitant l&#8217;ex\u00e9cution du contrat, au moment de la conclusion du contrat. Il peut s\u2019agir d\u2019incendie, de guerre, de manifestation, d\u2019\u00e9meute, de danger de guerre, d\u2019\u00e9tat d&#8217;alerte, de mobilisation, d\u2019hostilit\u00e9s, d\u2019embargo, de conditions atmosph\u00e9riques extr\u00eames, d\u2019\u00e9pid\u00e9mies, de gr\u00e8ve, de d\u00e9cisions gouvernementales, de troubles sociaux, de crise \u00e9nerg\u00e9tique.<\/p><p>Article 10. PRIX<\/p><p>10.1. Les prix fix\u00e9s sont libell\u00e9s en euros, TVA et tout autre droit ou taxe non compris. <br \/>10.2. La facture mentionne, en heures et quarts d\u2019heure, les temps de conduite, d&#8217;attente et de prestation au service du Client, arrondis au quart d&#8217;heure sup\u00e9rieur, avec un temps minimal de prestation de trois heures, m\u00eame si la dur\u00e9e effective du service s\u2019av\u00e8re plus courte. <br \/>10.3. Les frais de d\u00e9placement du Chauffeur priv\u00e9, depuis sa r\u00e9sidence jusqu\u2019au lieu de d\u00e9part fix\u00e9 par le Client et retour, sont toujours \u00e0 charge du Client. Ces frais de d\u00e9placement sont calcul\u00e9s de la mani\u00e8re suivante :<br \/>au prix co\u00fbtant, sur base des justificatifs, si le lieu de d\u00e9part du Client permet au Chauffeur priv\u00e9 de s\u2019y rendre en empruntant les transports en commun ;<br \/>sur base d\u2019une indemnit\u00e9 kilom\u00e9trique fix\u00e9e \u00e0 0,3178 \u20ac par kilom\u00e8tre, si les horaires ou le lieu de d\u00e9part du Client ne permet pas raisonnablement l\u2019utilisation des transports en commun. <br \/>Dans la mesure du possible, le Client sera inform\u00e9 au pr\u00e9alable des modalit\u00e9s de d\u00e9placement du Chauffeur priv\u00e9 en fonction du lieu de d\u00e9part choisi par le Client. <br \/>10.4. Les prestations des Chauffeurs priv\u00e9s effectu\u00e9es entre minuit et 06.00 du matin sont factur\u00e9es avec un suppl\u00e9ment de prix de 25 %. Les prestations effectu\u00e9es le dimanche entre 00.00 et 24.00 heures font \u00e9galement l\u2019objet d\u2019un suppl\u00e9ment de prix de 25 %. Toute heure au-del\u00e0 de 9 heures cons\u00e9cutives de prestation sera factur\u00e9e \u00e0 150%<br \/>10.5. Si la prestation du Chauffeur priv\u00e9 comprend une nuit\u00e9e, les heures de repos ne sont pas port\u00e9es en compte au Client. Dans ce cas, la p\u00e9riode de repos s\u2019\u00e9tend g\u00e9n\u00e9ralement de minuit \u00e0 sept heures de matin. Le Client doit pr\u00e9voir et prendre \u00e0 sa charge l\u2019h\u00e9bergement du Chauffeur priv\u00e9. <br \/>10.6. Par tranche de 8 heures de prestation, le Chauffeur priv\u00e9 a droit \u00e0 un repas aux frais du Client. Ce repas peut \u00eatre, ou non, pris en charge directement par le Client. Dans la n\u00e9gative, une indemnit\u00e9 de 15 \u20ac est factur\u00e9e au Client par MPC Services.<\/p><p>10.7. Les frais de carburant, de nettoyage ou d&#8217;entretien du v\u00e9hicule utilis\u00e9 pour le service prest\u00e9, de m\u00eame que les frais de parking et les p\u00e9ages, sont toujours \u00e0 charge du Client. Ces frais sont pay\u00e9s directement par le Client ou factur\u00e9. <br \/>10.8 Toute augmentation de prix, imposition, pr\u00e9l\u00e8vement ou autre charge qui interviendrait apr\u00e8s la remise de l&#8217;offre ou apr\u00e8s le d\u00e9but de l&#8217;entr\u00e9e en vigueur du contrat, pourra \u00eatre port\u00e9e en compte au Client.<br \/>Dans ce cas, MPC Services en avertira le Client dans le meilleur d\u00e9lai.<br \/>10.9 Si le chauffeur d\u00e9pose le client avec son v\u00e9hicule \u00e0 une adresse convenue et revient au point de d\u00e9part par ses propre moyens, les frais et le temps de d\u00e9placement jusqu&#8217;au point de d\u00e9part seront port\u00e9s en compte du client.<\/p><p>Article 11 FACTURATION<\/p><p>11.1. Nos factures sont \u00e9tablies sur base du d\u00e9compte effectu\u00e9 par le Chauffeur priv\u00e9 de son temps de prestation au service du Client. Ce d\u00e9compte sera sign\u00e9 pour accord par le Client \u00e0 la fin de la prestation, avant d\u2019\u00eatre transmis \u00e0 MPC Services par le Chauffeur priv\u00e9. <br \/>11.2. Toute contestation par le Client des heures de prestation factur\u00e9es devra \u00eatre faite par lettre recommand\u00e9e, adress\u00e9e \u00e0 MPC Services dans les 8 jours de l\u2019envoi de la facture. Pass\u00e9 ce d\u00e9lai, la plainte ne pourra \u00eatre prise en consid\u00e9ration.<\/p><p>Article 12. PAIEMENT<\/p><p>12.1. Les factures sont payables d\u00e8s leur r\u00e9ception sur le compte ING : BE35-3631-2899-0337de la soci\u00e9t\u00e9 MPC Services.<br \/>12.2. Les paiements faits avec retard, portent, de plein droit et sans mise en demeure, un int\u00e9r\u00eat conventionnel de 1% par mois civil, tout mois entam\u00e9 comptant pour un mois entier.<br \/>Au deuxi\u00e8me rappel, une p\u00e9nalit\u00e9 de 50 euros est d&#8217;office comptabilis\u00e9e.<br \/>En outre, tout retard de paiement annule les r\u00e9ductions de prix \u00e9ventuellement consenties au Client par ODD. <br \/>12.3. Les sommes vers\u00e9es par le Client \u00e0 MPC Services sont prioritairement utilis\u00e9es pour acquitter les \u00e9ventuels frais d\u00e9taill\u00e9s au point 12.4., puis ensuite, les factures impay\u00e9es dans l\u2019ordre de leur \u00e9mission en commen\u00e7ant par la plus ancienne, et ceci, ind\u00e9pendamment de la communication jointe par le Client \u00e0 son versement. <br \/>12.4. Les frais expos\u00e9s par MPC Services pour contraindre le Client au respect de ses obligations \u00e0 l\u2019\u00e9gard de MPC Services sont toujours \u00e0 charge du Client. Il peut s&#8217;agir : <br \/>&#8211; de frais d&#8217;avocats, <br \/>&#8211; de frais d&#8217;huissiers de justice, <br \/>&#8211; de frais de recouvrement <br \/>Ces frais s\u2019\u00e9l\u00e8vent \u00e0 15% du montant du contrat, avec un minimum de 60 \u20ac, somme pour laquelle aucun justificatif ne doit \u00eatre apport\u00e9. <br \/>12.5. Toute contestation relative \u00e0 une facture devra nous \u00eatre adress\u00e9e, par lettre recommand\u00e9e, dans les huit jours de son envoi.<\/p><p>Article 13. ASSURANCES<\/p><p>Le Client est tenu de contracter au minimum une assurance Responsabilit\u00e9 Civile conforme aux exigences impos\u00e9es par la loi belge relative \u00e0 l&#8217;assurance obligatoire de la responsabilit\u00e9 en mati\u00e8re de v\u00e9hicules automoteurs. Le Client est \u00e9galement tenu de contracter une assurance Protection des personnes. Ces assurances doivent \u00eatre valides pendant toute la dur\u00e9e du contrat. <br \/>Le v\u00e9hicule du Client doit \u00eatre en ordre d\u2019entretien et de contr\u00f4le technique. En cas de non respect de ces conditions, ni MPC Services, ni le Chauffeur priv\u00e9 ne pourront, en aucune mani\u00e8re, \u00eatre tenus pour responsables de pannes ou incidents techniques.<\/p><p>Article 14. RESPONSABILIT\u00c9<\/p><p>14.1. MPC Services ne peut \u00eatre tenu pour responsable de dommages quelconques caus\u00e9s par le chauffeur priv\u00e9 au Client ou \u00e0 des tiers, \u00e0 l\u2019occasion de ses prestations, si ce n\u2019est en cas de faute intentionnelle ou de faute lourde de sa part. <br \/>14.2. Le Client nous garantit contre les recours de tiers qui auraient subi un quelconque dommage suite aux prestations du Chauffeur priv\u00e9. <br \/>14.3 Sans pr\u00e9judice de l\u2019application des points 14.1. et 14.2., MPC Services ne peut \u00eatre tenu pour responsable des \u00e9l\u00e9ments suivants (sans que cette liste soit exhaustive) li\u00e9s aux prestations du Chauffeur priv\u00e9, sauf faute intentionnelle ou faute lourde de sa part :<br \/>&#8211; les cons\u00e9quences pour le Client ou pour des tiers du fait que le Client n\u2019ait pas atteint, ou n\u2019ait pas atteint dans le d\u00e9lai imparti, la destination pr\u00e9vue;<br \/>&#8211; les dommages ou frais encourus suite \u00e0 une infraction au code de la route ou un accident; <br \/>&#8211; les \u00e9ventuelles cons\u00e9quences sur le plan de l\u2019assurance v\u00e9hicule d\u2019un accident ou \u00e9v\u00e8nement similaire : p\u00e9nalit\u00e9 dans l\u2019\u00e9chelle bonus \u2013 malus, augmentation de la prime d\u2019assurance, augmentation de la franchise, tout autre risque quelconque propre \u00e0 l\u2019assur\u00e9;<br \/>&#8211; les dommages corporels aux passagers du v\u00e9hicule conduit par le Chauffeur priv\u00e9, ou \u00e0 des tiers;<br \/>&#8211; les d\u00e9g\u00e2ts mat\u00e9riels au v\u00e9hicule du Client ou aux biens de tiers;<br \/>&#8211; les d\u00e9g\u00e2ts survenus aux objets pr\u00e9sents dans le v\u00e9hicule conduit par le Chauffeur priv\u00e9, ou la perte de ceux-ci.<\/p><p>Article 15. TRAITEMENT DES PLAINTES<\/p><p>Pour \u00eatre prises en consid\u00e9ration, les plaintes doivent \u00eatre adress\u00e9e par \u00e9crit et envoi recommand\u00e9 \u00e0 MPC Services dans les 8 jours qui suivent la fin de la prestation concern\u00e9e. Les plaintes \u00e9mises en dehors de ce d\u00e9lai ne seront pas recevables.<\/p><p>Article 16. STIPULATION EN CHA\u00ceNE<\/p><p>En cas de cession compl\u00e8te ou partielle, et, ou de modifications d\u2019une entreprise cocontractante qui touchent des activit\u00e9s prest\u00e9es par MPC Services, l&#8217;autre partie est oblig\u00e9e d&#8217;imposer les pr\u00e9sentes conditions g\u00e9n\u00e9rales \u00e0 ses ayants-droits.<\/p><p>Article 17. CHANGEMENT DE D\u00c9NOMINATION<\/p><p>Les pr\u00e9sentes clauses restent int\u00e9gralement en vigueur au cas o\u00f9 MPC services change en tout ou en partie de d\u00e9nomination, de forme juridique ou de propri\u00e9taire.<\/p><p>Article 18. DROIT APPLICABLE<\/p><p>Tous les contrats auxquels s\u2019appliquent ces conditions g\u00e9n\u00e9rales, m\u00eame si les activit\u00e9s sont exerc\u00e9es \u00e0 l&#8217;\u00e9tranger, ainsi que les relations juridiques des parties qui en d\u00e9coulent, sont exclusivement r\u00e9gis par le droit belge et tout litige y relatif sera de la comp\u00e9tence exclusive des juridictions de l&#8217;arrondissement de Bruxelles.<\/p><p>Article 20. CLAUSE SALVATRICE<\/p><p>La non validit\u00e9 ou l\u2019ill\u00e9galit\u00e9 d\u2019une des clauses pr\u00e9vues dans les contrats (conditions sp\u00e9cifiques et g\u00e9n\u00e9rales) convenues entre parties, n\u2019entra\u00eene aucunement une invalidit\u00e9 ou une nullit\u00e9 des autres conditions du contrat conclu entre parties \u2013 clauses restant int\u00e9gralement valables<\/p><p>R\u00e8glementation et loi belge<\/p><p>Les v\u00e9hicules pr\u00e9cit\u00e9s seront mis \u00e0 disposition du locataire pour une dur\u00e9e de 3 heures minimum, seule\u00a0 circonstance dans laquelle une location de voiture avec chauffeur est l\u00e9galement autoris\u00e9e.<\/p><p>Suivant ordonnance du 27 avril 1995 et de l\u2019arr\u00eat\u00e9 du gouvernement de la r\u00e9gion de Bruxelles Capitale du 29\/03\/2007, relatifs aux services de taxis et aux voitures de location avec chauffeur.\u00a0 Dont les parties contractes d\u00e9clare s\u2019\u00eatre express\u00e9ment inform\u00e9e des dispositions de l\u2019ordonnance et de ses arr\u00eat\u00e9es d\u2019application et tout particuli\u00e8rement de celles applicable en mati\u00e8re d\u2019infraction, pour une prestation unique ou pour un ensemble de prestations d\u00e9finies ci-dessous\u00a0:<\/p><p>Prix minimum\u00a0: 90.00 \u20ac (voir mails en annexe de ce contrat) pour 3 heures<\/p><p>Prix \u00e0 factur\u00e9\u00a0: 150 de l\u2019heure htva et 5\u20ac du km htva, suivant prestation.<\/p><p>Le payement des diverses prestations du pr\u00e9sent contrat s\u2019effectuera apr\u00e8s r\u00e9ception d\u2019une facture au si\u00e8ge social du locataire ou au plus tard 10jours date de facturations suivant nos conditions g\u00e9n\u00e9ral de vente.<\/p><p>Tout payement d\u2019acompte est sujet d\u2019acception des conditions g\u00e9n\u00e9ral et responsabilit\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>MPC LUXURIOUS SERVICES &nbsp;our cars for rent Condition&nbsp;g\u00e9n\u00e9rale : Article 1. D\u00c9FINITIONS Dans les pr\u00e9sentes Conditions g\u00e9n\u00e9rales, les termes repris ci-apr\u00e8s sont d\u00e9finis comme suit &#8230; <a title=\"Terms of Service\" class=\"read-more\" href=\"https:\/\/mpc-services.be\/nl\/terms-of-service\/\" aria-label=\"Meer op Terms of Service\">Read More<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8445","page","type-page","status-publish","no-featured-image-padding"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Terms of Service - Location de Rolls Royce : Mpc Services<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mpc-services.be\/nl\/terms-of-service\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Terms of Service - Location de Rolls Royce : Mpc Services\" \/>\n<meta property=\"og:description\" content=\"MPC LUXURIOUS SERVICES &nbsp;our cars for rent Condition&nbsp;g\u00e9n\u00e9rale : Article 1. D\u00c9FINITIONS Dans les pr\u00e9sentes Conditions g\u00e9n\u00e9rales, les termes repris ci-apr\u00e8s sont d\u00e9finis comme suit ... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mpc-services.be\/nl\/terms-of-service\/\" \/>\n<meta property=\"og:site_name\" content=\"Location de Rolls Royce : Mpc Services\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/mpcservices.be\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-28T06:31:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mpc-services.be\\\/nl\\\/terms-of-service\\\/\",\"url\":\"https:\\\/\\\/mpc-services.be\\\/nl\\\/terms-of-service\\\/\",\"name\":\"Terms of Service - Location de Rolls Royce : Mpc Services\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mpc-services.be\\\/nl\\\/#website\"},\"datePublished\":\"2022-10-13T05:55:50+00:00\",\"dateModified\":\"2022-11-28T06:31:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mpc-services.be\\\/nl\\\/terms-of-service\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mpc-services.be\\\/nl\\\/terms-of-service\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mpc-services.be\\\/nl\\\/terms-of-service\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mpc-services.be\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Terms of Service\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mpc-services.be\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/mpc-services.be\\\/nl\\\/\",\"name\":\"Location de Rolls Royce : Mpc Services\",\"description\":\"Location de Rolls Royce\",\"publisher\":{\"@id\":\"https:\\\/\\\/mpc-services.be\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mpc-services.be\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mpc-services.be\\\/nl\\\/#organization\",\"name\":\"Location de Rolls Royce : Mpc Services\",\"url\":\"https:\\\/\\\/mpc-services.be\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/mpc-services.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mpc-services.be\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/mcp-rolls-royce-location.png\",\"contentUrl\":\"https:\\\/\\\/mpc-services.be\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/mcp-rolls-royce-location.png\",\"width\":960,\"height\":560,\"caption\":\"Location de Rolls Royce : Mpc Services\"},\"image\":{\"@id\":\"https:\\\/\\\/mpc-services.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/mpcservices.be\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Terms of Service - Location de Rolls Royce : Mpc Services","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mpc-services.be\/nl\/terms-of-service\/","og_locale":"nl_NL","og_type":"article","og_title":"Terms of Service - Location de Rolls Royce : Mpc Services","og_description":"MPC LUXURIOUS SERVICES &nbsp;our cars for rent Condition&nbsp;g\u00e9n\u00e9rale : Article 1. D\u00c9FINITIONS Dans les pr\u00e9sentes Conditions g\u00e9n\u00e9rales, les termes repris ci-apr\u00e8s sont d\u00e9finis comme suit ... Read More","og_url":"https:\/\/mpc-services.be\/nl\/terms-of-service\/","og_site_name":"Location de Rolls Royce : Mpc Services","article_publisher":"https:\/\/m.facebook.com\/mpcservices.be\/","article_modified_time":"2022-11-28T06:31:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"11 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mpc-services.be\/nl\/terms-of-service\/","url":"https:\/\/mpc-services.be\/nl\/terms-of-service\/","name":"Terms of Service - Location de Rolls Royce : Mpc Services","isPartOf":{"@id":"https:\/\/mpc-services.be\/nl\/#website"},"datePublished":"2022-10-13T05:55:50+00:00","dateModified":"2022-11-28T06:31:51+00:00","breadcrumb":{"@id":"https:\/\/mpc-services.be\/nl\/terms-of-service\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mpc-services.be\/nl\/terms-of-service\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mpc-services.be\/nl\/terms-of-service\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mpc-services.be\/nl\/"},{"@type":"ListItem","position":2,"name":"Terms of Service"}]},{"@type":"WebSite","@id":"https:\/\/mpc-services.be\/nl\/#website","url":"https:\/\/mpc-services.be\/nl\/","name":"Location de Rolls Royce : Mpc Services","description":"Location de Rolls Royce","publisher":{"@id":"https:\/\/mpc-services.be\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mpc-services.be\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/mpc-services.be\/nl\/#organization","name":"Location de Rolls Royce : Mpc Services","url":"https:\/\/mpc-services.be\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/mpc-services.be\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/mpc-services.be\/wp-content\/uploads\/2022\/10\/mcp-rolls-royce-location.png","contentUrl":"https:\/\/mpc-services.be\/wp-content\/uploads\/2022\/10\/mcp-rolls-royce-location.png","width":960,"height":560,"caption":"Location de Rolls Royce : Mpc Services"},"image":{"@id":"https:\/\/mpc-services.be\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/mpcservices.be\/"]}]}},"_links":{"self":[{"href":"https:\/\/mpc-services.be\/nl\/wp-json\/wp\/v2\/pages\/8445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mpc-services.be\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mpc-services.be\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mpc-services.be\/nl\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/mpc-services.be\/nl\/wp-json\/wp\/v2\/comments?post=8445"}],"version-history":[{"count":0,"href":"https:\/\/mpc-services.be\/nl\/wp-json\/wp\/v2\/pages\/8445\/revisions"}],"wp:attachment":[{"href":"https:\/\/mpc-services.be\/nl\/wp-json\/wp\/v2\/media?parent=8445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}